
{"id":428442,"date":"2026-03-28T10:52:03","date_gmt":"2026-03-28T09:52:03","guid":{"rendered":"https:\/\/www.navigazionelaghi.it\/?post_type=avvisi&#038;p=428442"},"modified":"2026-03-28T10:52:03","modified_gmt":"2026-03-28T09:52:03","slug":"bellagio-ferry-service-suspended-till-1st-april-2026","status":"publish","type":"avvisi","link":"https:\/\/www.navigazionelaghi.it\/en\/notices\/bellagio-ferry-service-suspended-till-1st-april-2026\/","title":{"rendered":"Bellagio ferry service suspended till 1st April 2026"},"content":{"rendered":"<p>In esito agli approfondimenti effettuati sui danneggiamenti causati dal maltempo dei giorni scorsi alle strutture del pontile traghetto di Bellagio, si conferma la <strong>sospensione del servizio di trasporto veicoli sino a mercoled\u00ec 1 aprile 2026<\/strong> per consentire le necessarie lavorazioni di ripristino delle funzionalit\u00e0 nella massima sicurezza.<\/p>\n<p>Sul sito internet istituzionale e tramite avvisi in biglietteria, sar\u00e0 comunicato ogni ulteriore aggiornamento.<\/p>\n<p>Le partenze e gli arrivi del servizio autotraghetto da\/per Bellagio verranno effettuati per il solo trasporto di persone dal pontile n\u00b0 2 di piazza Mazzini.<\/p>\n<p>Ci scusiamo per il disagio<\/p>\n","protected":false},"featured_media":0,"template":"","lago":[182],"class_list":["post-428442","avvisi","type-avvisi","status-publish","hentry","lago-lake_como"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bellagio ferry service suspended till 1st April 2026 - Navigazione Laghi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.navigazionelaghi.it\/en\/notices\/bellagio-ferry-service-suspended-till-1st-april-2026\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bellagio ferry service suspended till 1st April 2026 - Navigazione Laghi\" \/>\n<meta property=\"og:description\" content=\"In esito agli approfondimenti effettuati sui danneggiamenti causati dal maltempo dei giorni scorsi alle [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.navigazionelaghi.it\/en\/notices\/bellagio-ferry-service-suspended-till-1st-april-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Navigazione Laghi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GestioneNavigazioneLaghi\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.navigazionelaghi.it\/wp-content\/uploads\/2023\/02\/navigazione-laghi-logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@NavLaghi\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.navigazionelaghi.it\\\/en\\\/notices\\\/bellagio-ferry-service-suspended-till-1st-april-2026\\\/\",\"url\":\"https:\\\/\\\/www.navigazionelaghi.it\\\/en\\\/notices\\\/bellagio-ferry-service-suspended-till-1st-april-2026\\\/\",\"name\":\"Bellagio ferry service suspended till 1st April 2026 - Navigazione Laghi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.navigazionelaghi.it\\\/en\\\/#website\"},\"datePublished\":\"2026-03-28T09:52:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.navigazionelaghi.it\\\/en\\\/notices\\\/bellagio-ferry-service-suspended-till-1st-april-2026\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.navigazionelaghi.it\\\/en\\\/notices\\\/bellagio-ferry-service-suspended-till-1st-april-2026\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.navigazionelaghi.it\\\/en\\\/notices\\\/bellagio-ferry-service-suspended-till-1st-april-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.navigazionelaghi.it\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Notices\",\"item\":\"https:\\\/\\\/www.navigazionelaghi.it\\\/en\\\/notices\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bellagio ferry service suspended till 1st April 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.navigazionelaghi.it\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.navigazionelaghi.it\\\/en\\\/\",\"name\":\"Navigazione Laghi\",\"description\":\"Lago Maggiore | Lago di Garda | Lago di Como\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.navigazionelaghi.it\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.navigazionelaghi.it\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.navigazionelaghi.it\\\/en\\\/#organization\",\"name\":\"Navigazione Laghi\",\"url\":\"https:\\\/\\\/www.navigazionelaghi.it\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.navigazionelaghi.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.navigazionelaghi.it\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.navigazionelaghi.it\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo.png\",\"width\":250,\"height\":270,\"caption\":\"Navigazione Laghi\"},\"image\":{\"@id\":\"https:\\\/\\\/www.navigazionelaghi.it\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GestioneNavigazioneLaghi\\\/\",\"https:\\\/\\\/x.com\\\/NavLaghi\",\"https:\\\/\\\/www.instagram.com\\\/gestionenavigazionelaghi\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/navigazionelaghi\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCvvXix50TzIdtV0gSwl-aOQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bellagio ferry service suspended till 1st April 2026 - Navigazione Laghi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.navigazionelaghi.it\/en\/notices\/bellagio-ferry-service-suspended-till-1st-april-2026\/","og_locale":"en_US","og_type":"article","og_title":"Bellagio ferry service suspended till 1st April 2026 - Navigazione Laghi","og_description":"In esito agli approfondimenti effettuati sui danneggiamenti causati dal maltempo dei giorni scorsi alle [&hellip;]","og_url":"https:\/\/www.navigazionelaghi.it\/en\/notices\/bellagio-ferry-service-suspended-till-1st-april-2026\/","og_site_name":"Navigazione Laghi","article_publisher":"https:\/\/www.facebook.com\/GestioneNavigazioneLaghi\/","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.navigazionelaghi.it\/wp-content\/uploads\/2023\/02\/navigazione-laghi-logo.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@NavLaghi","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.navigazionelaghi.it\/en\/notices\/bellagio-ferry-service-suspended-till-1st-april-2026\/","url":"https:\/\/www.navigazionelaghi.it\/en\/notices\/bellagio-ferry-service-suspended-till-1st-april-2026\/","name":"Bellagio ferry service suspended till 1st April 2026 - Navigazione Laghi","isPartOf":{"@id":"https:\/\/www.navigazionelaghi.it\/en\/#website"},"datePublished":"2026-03-28T09:52:03+00:00","breadcrumb":{"@id":"https:\/\/www.navigazionelaghi.it\/en\/notices\/bellagio-ferry-service-suspended-till-1st-april-2026\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.navigazionelaghi.it\/en\/notices\/bellagio-ferry-service-suspended-till-1st-april-2026\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.navigazionelaghi.it\/en\/notices\/bellagio-ferry-service-suspended-till-1st-april-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.navigazionelaghi.it\/en\/"},{"@type":"ListItem","position":2,"name":"Notices","item":"https:\/\/www.navigazionelaghi.it\/en\/notices\/"},{"@type":"ListItem","position":3,"name":"Bellagio ferry service suspended till 1st April 2026"}]},{"@type":"WebSite","@id":"https:\/\/www.navigazionelaghi.it\/en\/#website","url":"https:\/\/www.navigazionelaghi.it\/en\/","name":"Navigazione Laghi","description":"Lago Maggiore | Lago di Garda | Lago di Como","publisher":{"@id":"https:\/\/www.navigazionelaghi.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.navigazionelaghi.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.navigazionelaghi.it\/en\/#organization","name":"Navigazione Laghi","url":"https:\/\/www.navigazionelaghi.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.navigazionelaghi.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.navigazionelaghi.it\/wp-content\/uploads\/2022\/05\/logo.png","contentUrl":"https:\/\/www.navigazionelaghi.it\/wp-content\/uploads\/2022\/05\/logo.png","width":250,"height":270,"caption":"Navigazione Laghi"},"image":{"@id":"https:\/\/www.navigazionelaghi.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GestioneNavigazioneLaghi\/","https:\/\/x.com\/NavLaghi","https:\/\/www.instagram.com\/gestionenavigazionelaghi\/","https:\/\/www.linkedin.com\/company\/navigazionelaghi\/","https:\/\/www.youtube.com\/channel\/UCvvXix50TzIdtV0gSwl-aOQ"]}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 23:06:02","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"lago","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.navigazionelaghi.it\/en\/wp-json\/wp\/v2\/avvisi\/428442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.navigazionelaghi.it\/en\/wp-json\/wp\/v2\/avvisi"}],"about":[{"href":"https:\/\/www.navigazionelaghi.it\/en\/wp-json\/wp\/v2\/types\/avvisi"}],"wp:attachment":[{"href":"https:\/\/www.navigazionelaghi.it\/en\/wp-json\/wp\/v2\/media?parent=428442"}],"wp:term":[{"taxonomy":"lago","embeddable":true,"href":"https:\/\/www.navigazionelaghi.it\/en\/wp-json\/wp\/v2\/lago?post=428442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}